{"id":4,"date":"2020-12-03T19:13:47","date_gmt":"2020-12-03T19:13:47","guid":{"rendered":"https:\/\/justdeeds.org\/es\/?page_id=4"},"modified":"2021-03-10T22:12:05","modified_gmt":"2021-03-10T22:12:05","slug":"home","status":"publish","type":"page","link":"https:\/\/justdeeds.org\/es\/","title":{"rendered":"Inicio"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page_home.php","meta":{"_acf_changed":false,"nf_dc_page":"","footnotes":""},"class_list":["post-4","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inicio - El Proyecto de Just Deeds<\/title>\n<meta name=\"description\" content=\"Se han utilizado convenios discriminatorios para evitar que las personas de color compren casas en ciertos vecindarios de Minnesota. El resultado es un siglo de comunidades segregadas. Juntos, podemos reconocer esta discriminaci\u00f3n, quitar estos convenios y sentar las bases para comunidades m\u00e1s inclusivas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/justdeeds.org\/es\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inicio - El Proyecto de Just Deeds\" \/>\n<meta property=\"og:description\" content=\"Se han utilizado convenios discriminatorios para evitar que las personas de color compren casas en ciertos vecindarios de Minnesota. El resultado es un siglo de comunidades segregadas. Juntos, podemos reconocer esta discriminaci\u00f3n, quitar estos convenios y sentar las bases para comunidades m\u00e1s inclusivas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/justdeeds.org\/es\/\" \/>\n<meta property=\"og:site_name\" content=\"El Proyecto de Just Deeds\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/justdeedsmn\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-10T22:12:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@justdeedsmn\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/\",\"url\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/\",\"name\":\"Inicio - El Proyecto de Just Deeds\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/#website\"},\"datePublished\":\"2020-12-03T19:13:47+00:00\",\"dateModified\":\"2021-03-10T22:12:05+00:00\",\"description\":\"Se han utilizado convenios discriminatorios para evitar que las personas de color compren casas en ciertos vecindarios de Minnesota. El resultado es un siglo de comunidades segregadas. Juntos, podemos reconocer esta discriminaci\u00f3n, quitar estos convenios y sentar las bases para comunidades m\u00e1s inclusivas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/justdeeds.org\\\/es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/\",\"name\":\"El Proyecto de Just Deeds\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/#organization\",\"name\":\"El Proyecto de Just Deeds\",\"url\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/Just-Deeds-Logo_TM_Social_RGB_F_FB_170x170.jpg\",\"contentUrl\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/Just-Deeds-Logo_TM_Social_RGB_F_FB_170x170.jpg\",\"width\":709,\"height\":709,\"caption\":\"El Proyecto de Just Deeds\"},\"image\":{\"@id\":\"https:\\\/\\\/justdeeds.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/justdeedsmn\",\"https:\\\/\\\/x.com\\\/justdeedsmn\",\"https:\\\/\\\/www.instagram.com\\\/justdeedsmn\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/just-deeds-mn\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCjR7zeI-1oTTdr4wCv3lnUA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inicio - El Proyecto de Just Deeds","description":"Se han utilizado convenios discriminatorios para evitar que las personas de color compren casas en ciertos vecindarios de Minnesota. El resultado es un siglo de comunidades segregadas. Juntos, podemos reconocer esta discriminaci\u00f3n, quitar estos convenios y sentar las bases para comunidades m\u00e1s inclusivas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/justdeeds.org\/es\/","og_locale":"en_US","og_type":"article","og_title":"Inicio - El Proyecto de Just Deeds","og_description":"Se han utilizado convenios discriminatorios para evitar que las personas de color compren casas en ciertos vecindarios de Minnesota. El resultado es un siglo de comunidades segregadas. Juntos, podemos reconocer esta discriminaci\u00f3n, quitar estos convenios y sentar las bases para comunidades m\u00e1s inclusivas.","og_url":"https:\/\/justdeeds.org\/es\/","og_site_name":"El Proyecto de Just Deeds","article_publisher":"https:\/\/www.facebook.com\/justdeedsmn","article_modified_time":"2021-03-10T22:12:05+00:00","twitter_card":"summary_large_image","twitter_site":"@justdeedsmn","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/justdeeds.org\/es\/","url":"https:\/\/justdeeds.org\/es\/","name":"Inicio - El Proyecto de Just Deeds","isPartOf":{"@id":"https:\/\/justdeeds.org\/es\/#website"},"datePublished":"2020-12-03T19:13:47+00:00","dateModified":"2021-03-10T22:12:05+00:00","description":"Se han utilizado convenios discriminatorios para evitar que las personas de color compren casas en ciertos vecindarios de Minnesota. El resultado es un siglo de comunidades segregadas. Juntos, podemos reconocer esta discriminaci\u00f3n, quitar estos convenios y sentar las bases para comunidades m\u00e1s inclusivas.","breadcrumb":{"@id":"https:\/\/justdeeds.org\/es\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/justdeeds.org\/es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/justdeeds.org\/es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/justdeeds.org\/es\/"},{"@type":"ListItem","position":2,"name":"Inicio"}]},{"@type":"WebSite","@id":"https:\/\/justdeeds.org\/es\/#website","url":"https:\/\/justdeeds.org\/es\/","name":"El Proyecto de Just Deeds","description":"","publisher":{"@id":"https:\/\/justdeeds.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/justdeeds.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/justdeeds.org\/es\/#organization","name":"El Proyecto de Just Deeds","url":"https:\/\/justdeeds.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/justdeeds.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/justdeeds.org\/es\/wp-content\/uploads\/sites\/2\/2021\/03\/Just-Deeds-Logo_TM_Social_RGB_F_FB_170x170.jpg","contentUrl":"https:\/\/justdeeds.org\/es\/wp-content\/uploads\/sites\/2\/2021\/03\/Just-Deeds-Logo_TM_Social_RGB_F_FB_170x170.jpg","width":709,"height":709,"caption":"El Proyecto de Just Deeds"},"image":{"@id":"https:\/\/justdeeds.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/justdeedsmn","https:\/\/x.com\/justdeedsmn","https:\/\/www.instagram.com\/justdeedsmn\/","https:\/\/www.linkedin.com\/company\/just-deeds-mn\/","https:\/\/www.youtube.com\/channel\/UCjR7zeI-1oTTdr4wCv3lnUA"]}]}},"_links":{"self":[{"href":"https:\/\/justdeeds.org\/es\/wp-json\/wp\/v2\/pages\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/justdeeds.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/justdeeds.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/justdeeds.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/justdeeds.org\/es\/wp-json\/wp\/v2\/comments?post=4"}],"version-history":[{"count":6,"href":"https:\/\/justdeeds.org\/es\/wp-json\/wp\/v2\/pages\/4\/revisions"}],"predecessor-version":[{"id":1098,"href":"https:\/\/justdeeds.org\/es\/wp-json\/wp\/v2\/pages\/4\/revisions\/1098"}],"wp:attachment":[{"href":"https:\/\/justdeeds.org\/es\/wp-json\/wp\/v2\/media?parent=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}